{"id":11171,"date":"2025-05-26T09:57:03","date_gmt":"2025-05-26T07:57:03","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=11171"},"modified":"2025-05-26T09:57:03","modified_gmt":"2025-05-26T07:57:03","slug":"apertura-bandi-borse-di-ricerca-fondazione-umberto-veronesi-2026","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/apertura-bandi-borse-di-ricerca-fondazione-umberto-veronesi-2026\/","title":{"rendered":"Apertura bandi borse di ricerca Fondazione Umberto Veronesi 2026"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Apertura bandi borse di ricerca FUV 2026<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p>Gentili Soci,<\/p>\n<p>siamo a comunicare che sono aperti i bandi per il 2026 di Fondazione Veronesi.<\/p>\n<p>In particolare:<\/p>\n<p>Il <strong>Bando Experimental<\/strong> \u00e8 destinato a ricercatori post-dottorato che svolgano ricerca nei migliori istituti nazionali nell\u2019ambito della prevenzione, diagnosi e cura dei tumori; mette a disposizione, per l\u2019anno <strong>2026<\/strong>, <strong>100 borse di ricerca<\/strong> (75 di durata annuale e 25 biennali) nelle aree dell\u2019oncologia e degli stili di vita per la prevenzione oncologica (impatto di alimentazione, attivit\u00e0 fisica, fumo e inquinamento).<\/p>\n<p>In occasione del centenario della nascita del fondatore Umberto Veronesi, nel 2026 \u00e8 stato istituito un bando Clinico indirizzato a medici impegnati in ricerca clinica nei migliori centri di cura nazionali, che svolgano progetti di ricerca innovativi in chirurgia, radiologia e terapie oncologiche per migliorare la vita dei pazienti. Le borse a disposizione sono 10 di durata annuale.<\/p>\n<p>I bandi e le modalit\u00e0 di applicazione sono disponibili al sito:<\/p>\n<p><strong><a href=\"https:\/\/grant.fondazioneveronesi.it\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/grant.fondazioneveronesi.it\/&amp;source=gmail&amp;ust=1748327245771000&amp;usg=AOvVaw3wJw5GMvrnlE5BwjjP8EG4\">https:\/\/grant.fondazioneverone<wbr \/>si.it\/<\/a>&lt;<a href=\"https:\/\/urlsand.esvalabs.com\/?u=https%3A%2F%2Fgrant.fondazioneveronesi.it%2F&amp;e=8c00e339&amp;h=7d6596d7&amp;f=y&amp;p=y\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/urlsand.esvalabs.com\/?u%3Dhttps%253A%252F%252Fgrant.fondazioneveronesi.it%252F%26e%3D8c00e339%26h%3D7d6596d7%26f%3Dy%26p%3Dy&amp;source=gmail&amp;ust=1748327245771000&amp;usg=AOvVaw0EI8_9g24s3-KJlPyDLuD8\">https:\/\/urlsand.<wbr \/>esvalabs.com\/?u=https%3A%2F%<wbr \/>2Fgrant.fondazioneveronesi.it%<wbr \/>2F&amp;e=8c00e339&amp;h=7d6596d7&amp;f=y&amp;<wbr \/>p=y<\/a>&gt;<\/strong><\/p>\n<p>I bandi saranno aperti fino al 18 luglio 2025, ore 17:59<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-11171","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/11171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=11171"}],"version-history":[{"count":1,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/11171\/revisions"}],"predecessor-version":[{"id":11172,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/11171\/revisions\/11172"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=11171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=11171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=11171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}