{"id":7936,"date":"2022-03-04T10:35:12","date_gmt":"2022-03-04T09:35:12","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=7936"},"modified":"2022-03-04T10:35:12","modified_gmt":"2022-03-04T09:35:12","slug":"bando-di-concorso-gilead-international-research-scholars-program-nellarea-delle-patologie-oncoematologiche","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/bando-di-concorso-gilead-international-research-scholars-program-nellarea-delle-patologie-oncoematologiche\/","title":{"rendered":"Bando di concorso Gilead &#8211; International Research Scholars Program nell\u2019area delle Patologie oncoematologiche"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Bando di concorso Gilead &#8211; International Research Scholars Program nell\u2019area delle Patologie oncoematologiche<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><div>Siamo lieti di comunicarle l&#8217;apertura del Gilead Sciences <strong>International\u00a0<\/strong><strong>Research<\/strong>\u00a0<strong>Scholars<\/strong>\u00a0<strong>Program<\/strong>, Bando di concorso promosso da Gilead per sostenere la ricerca scientifica innovativa di giovani ricercatori nel campo delle Patologie oncoematologiche.<\/div>\n<div><\/div>\n<div>Il Bando offre un supporto economico di 130.000 dollari, da utilizzare per la realizzazione di un progetto biennale di ricerca nel campo delle patologie oncoematologiche.<\/div>\n<div>L&#8217;ammontare del premio verr\u00e0 erogato in due tranche annuali del valore massimo di 65.000 dollari per anno.<\/div>\n<div>L&#8217;erogazione della seconda tranche sar\u00e0 subordinata alla presentazione di un report del lavoro svolto nel primo anno e alla sua approvazione da parte dello\u00a0<em>Scientific Review Committee\u00a0<\/em>del Bando.<\/div>\n<div>La presentazione dei progetti potr\u00e0 avvenire fino a luned\u00ec<strong> 21 marzo 2022.<\/strong><\/div>\n<div>Per ulteriori informazioni si rimanda al sito dedicato:\u00a0<a href=\"https:\/\/researchscholars.gilead.com\/en\/intl_hematologic_malignancies_portal\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/researchscholars.gilead.com\/en\/intl_hematologic_malignancies_portal&amp;source=gmail&amp;ust=1646472149590000&amp;usg=AOvVaw1KJn-Gjr13gA2D-0jViAbr\">https:\/\/researchscholars.<wbr \/>gilead.com\/en\/intl_<wbr \/>hematologic_malignancies_<wbr \/>portal<\/a><\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7936","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/7936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=7936"}],"version-history":[{"count":1,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/7936\/revisions"}],"predecessor-version":[{"id":7937,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/7936\/revisions\/7937"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=7936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=7936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=7936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}