{"id":8067,"date":"2022-04-13T11:41:40","date_gmt":"2022-04-13T09:41:40","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=8067"},"modified":"2022-04-13T11:42:32","modified_gmt":"2022-04-13T09:42:32","slug":"pinacoteca-volante-gioco-e-arte-in-oncologia","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/pinacoteca-volante-gioco-e-arte-in-oncologia\/","title":{"rendered":"Pinacoteca Volante &#8211; Gioco e Arte in Oncologia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Combattere la paura liberando la fantasia e l&#8217;immaginazione<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p>E&#8217; l&#8217;aspirazione di &#8216;Scuola e Giochi in Corsia&#8217;, un programma realizzato da Amgen e AIEOP per sostenere bambini e adolescenti con leucemie e patologie ematologiche nel lungo percorso di ospedalizzazione.<\/p>\n<p>Acquerelli, tempere, costruzioni e fotografie per imparare e ritrovare momenti di spensieratezza grazie al supporto di insegnanti e psico-oncologi nei reparti. L&#8217;iniziativa \u00e8 raccontata nel volume &#8216;Pinacoteca Volante &#8211; Gioco e Arte in Oncologia&#8217;, il libro che raccoglie le opere e le storie dei ragazzi coinvolti nel laboratorio del Centro di Oncoematologia Pediatrica dell&#8217;IRCCS -Azienda Ospedaliero Universitaria di Bologna.<\/p>\n<p>Il volume sar\u00e0 disponibile presso la Segreteria AIEOP.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><p><img decoding=\"async\" class=\"alignnone size-full wp-image-8068\" src=\"https:\/\/www.aieop.org\/web\/wp-content\/uploads\/2022\/04\/Aieop.jpg\" alt=\"\" width=\"426\" height=\"768\" \/><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8067","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=8067"}],"version-history":[{"count":1,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8067\/revisions"}],"predecessor-version":[{"id":8070,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8067\/revisions\/8070"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=8067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=8067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=8067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}