{"id":8480,"date":"2022-10-26T11:05:53","date_gmt":"2022-10-26T09:05:53","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=8480"},"modified":"2022-10-26T11:07:05","modified_gmt":"2022-10-26T09:07:05","slug":"bando","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/bando\/","title":{"rendered":"BANDO"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><h3>AZIENDA OSPEDALIERO-UNIVERSITARIA POLICLINICO UMBERTO I DI ROMA<\/h3><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p>Concorso pubblico, per titoli ed esami, per la copertura di cinque posti di dirigente medico a tempo indeterminato, disciplina di pediatria, per l\u2019UOC Oncologia pediatrica.<br \/>\nIn esecuzione della deliberazione n. 585 del 26 settembre 2022, parzialmente modificata con delibera n. 606 del 3 ottobre 2022 \u00e8 indetto concorso pubblico, per titoli ed esami, per la copertura a tempo indeterminato di cinque posti di dirigente medico, disciplina di pediatria per le esigenze della U.O.C. Oncologia pediatrica &#8211; BC14\/22.<br \/>\nIl termine per la presentazione della domanda, da produrre esclusivamente tramite procedura telematica, scade il trentesimo giorno successivo alla data di pubblicazione del presente avviso nella Gazzetta Ufficiale della Repubblica italiana &#8211; 4\u00aa Serie speciale \u00abConcorsi ed esami\u00bb.<br \/>\nIl testo integrale del bando \u00e8 consultabile nel Bollettino Ufficiale della Regione Lazio n. 84 dell\u201911 ottobre 2022 e sul sito dell\u2019Azienda ospedaliero-universitaria Policlinico Umberto I www.policlinicoumberto1.it sezione \u00abBandi di concorso\u00bb.<\/p>\n<p><strong>Scadenza: 17\/11\/2022 11:59 pm<\/strong><\/p>\n<\/div><div class=\"fusion-text fusion-text-2\"><div class=\"video-shortcode\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"1k0qt31Cfl\">\n<p><a href=\"https:\/\/www.policlinicoumberto1.it\/bando-concorso\/concorso-pubblico-per-titoli-ed-esami-per-la-copertura-di-n-5-posti-di-dirigente-medico-disciplina-pediatria-per-le-esigenze-della-uoc-oncologia-pediatrica-bc14-22\/\">Concorso pubblico, per titoli ed esami, per la copertura di n. 5 posti di Dirigente Medico &#8211; disciplina Pediatria per le esigenze della UOC Oncologia Pediatrica \u2013 BC14\/22<\/a><\/p>\n<\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Concorso pubblico, per titoli ed esami, per la copertura di n. 5 posti di Dirigente Medico &#8211; disciplina Pediatria per le esigenze della UOC Oncologia Pediatrica \u2013 BC14\/22&#8221; &#8212; Policlinico Umberto 1\" src=\"https:\/\/www.policlinicoumberto1.it\/bando-concorso\/concorso-pubblico-per-titoli-ed-esami-per-la-copertura-di-n-5-posti-di-dirigente-medico-disciplina-pediatria-per-le-esigenze-della-uoc-oncologia-pediatrica-bc14-22\/embed\/#?secret=1k0qt31Cfl\" data-secret=\"1k0qt31Cfl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8480","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=8480"}],"version-history":[{"count":2,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8480\/revisions"}],"predecessor-version":[{"id":8482,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8480\/revisions\/8482"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=8480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=8480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=8480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}