{"id":8746,"date":"2022-12-22T14:44:14","date_gmt":"2022-12-22T13:44:14","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=8746"},"modified":"2022-12-22T14:48:04","modified_gmt":"2022-12-22T13:48:04","slug":"cari-auguri","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/cari-auguri\/","title":{"rendered":"Cari Auguri"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Auguri<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xdj266r x126k92a\">\n<div dir=\"auto\">Cari Soci,<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">a nome del consiglio direttivo AIEOP, in queste giornate Natalizie, vi partecipo gli Auguri per le imminenti Festivit\u00e0.<\/div>\n<div dir=\"auto\">La nostra Associazione con il congresso in presenza a Torino ha dato ancora una volta prova di grande vitalit\u00e0, segnale ancora pi\u00f9 apprezzato dopo la pandemia che aveva imposto un temporaneo stop agli eventi in presenza.<\/div>\n<div dir=\"auto\">L\u2019Associazione ha mantenuto la sua attivit\u00e0 attraverso protocolli, studi internazionali, pubblicazioni scientifiche, interazioni con altre Societ\u00e0 scientifiche pediatriche e dell&#8217;adulto sia italiane che straniere.<\/div>\n<div dir=\"auto\">Siamo cresciuti in numero, ma parallelamente sono aumentate per numero e complessit\u00e0 anche le progettualit\u00e0 comuni: la presenza di tanti giovani \u00e8 prova fattiva della vitalit\u00e0 della nostra Associazione. Il loro entusiasmo sia da esempio coinvolgente e stimolante per tutti.<\/div>\n<div dir=\"auto\">Le giornate AIEOP rivestono un ruolo cruciale quale luogo di scambio di opinioni e di progetti: contiamo sulla vostra partecipazione fattiva e collaborativa anche nel corso del 2023.<\/div>\n<div dir=\"auto\">Il vostro contributo alle iniziative AIEOP permette di consolidare la consapevolezza che la nostra Associazione si pone come un riferimento ormai imprescindibile per tutti coloro che si impegnano nel campo dell&#8217;oncologia e dell&#8217;ematologia pediatrica italiana.<\/div>\n<div dir=\"auto\">Nella speranza di continuare ad incontrarci nel nuovo anno, impegnandoci a fare sempre meglio, a nome di tutto il Consiglio Direttivo rivolgo a tutti voi e alle vostre famiglie un caro Augurio per un sereno Natale e per ricco e prospero Anno Nuovo.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Il Presidente<\/div>\n<div dir=\"auto\">Dottor Arcangelo Prete<\/div>\n<\/div>\n<\/div><div class=\"fusion-text fusion-text-2\"><p><img decoding=\"async\" class=\"alignnone wp-image-8747\" src=\"https:\/\/www.aieop.org\/web\/wp-content\/uploads\/2022\/12\/shutterstock_2224472243.jpg\" alt=\"\" width=\"500\" height=\"334\" \/><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8746","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=8746"}],"version-history":[{"count":3,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8746\/revisions"}],"predecessor-version":[{"id":8751,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/8746\/revisions\/8751"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=8746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=8746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=8746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}