{"id":9221,"date":"2023-03-23T14:36:46","date_gmt":"2023-03-23T13:36:46","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=9221"},"modified":"2023-03-23T14:36:59","modified_gmt":"2023-03-23T13:36:59","slug":"bandi-fondazione-guido-berlucchi-2023-per-la-ricerca-in-oncologia","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/bandi-fondazione-guido-berlucchi-2023-per-la-ricerca-in-oncologia\/","title":{"rendered":"Bandi Fondazione Guido Berlucchi 2023 per la ricerca in oncologia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><h3 class=\"mb-4 text-sie-red\">Bandi Fondazione Guido Berlucchi 2023 per la ricerca in oncologia<\/h3><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p>Segnaliamo due bandi promossi dalla Fondazione Berlucchi a supporto della ricerca oncologica:<\/p>\n<ul>\n<li><b>Young Researchers Mobility Program<\/b>\u00a0a sostegno delle spese di mobilit\u00e0 di giovani ricercatori per un periodo di formazione all\u2019estero da 1 a 6 mesi \u2013\u00a0<b>scadenza 5 Maggio 2023<\/b><\/li>\n<li><b>Mini Grant Programme<\/b>\u00a0volto a finanziare le spese correnti sostenute da giovani ricercatori impegnati nella ricerca di base \u2013\u00a0<b>scadenza 16 Maggio 2023<\/b><\/li>\n<\/ul>\n<p>I bandi e la relativa modulistica sono consultabili al seguente link:\u00a0<a href=\"https:\/\/www.fondazioneberlucchi.org\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fondazioneberlucchi.org\/<\/a><\/p>\n<\/div><div class=\"fusion-text fusion-text-2\"><div><a href=\"https:\/\/www.siematologia.it\/storage\/siematologia\/article\/pdf\/158\/2-WEB_Call2023_Mobility.pdf\" target=\"_blank\" rel=\"noopener\">Scarica il bando Mobility<\/a><\/div>\n<div><a href=\"https:\/\/www.siematologia.it\/storage\/siematologia\/article\/pdf\/158\/2-WEB_Call2023_MiniGrant.pdf\" target=\"_blank\" rel=\"noopener\">Scarica il bando Mini Grant<\/a><\/div>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-9221","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=9221"}],"version-history":[{"count":1,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9221\/revisions"}],"predecessor-version":[{"id":9222,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9221\/revisions\/9222"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=9221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=9221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=9221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}