{"id":9450,"date":"2023-05-26T08:48:31","date_gmt":"2023-05-26T06:48:31","guid":{"rendered":"https:\/\/www.aieop.org\/web\/?p=9450"},"modified":"2023-05-26T08:48:31","modified_gmt":"2023-05-26T06:48:31","slug":"oncologia-e-cure-palliative-pediatriche-alla-ricerca-di-unintegrazione-possibile","status":"publish","type":"post","link":"https:\/\/www.aieop.org\/web\/oncologia-e-cure-palliative-pediatriche-alla-ricerca-di-unintegrazione-possibile\/","title":{"rendered":"Oncologia e cure palliative pediatriche: alla ricerca di un\u2019integrazione possibile"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 blog-article nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:120px;--awb-padding-left:120px;--awb-margin-top:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><p>La stessa lingua per iniziare a parlarsi<br \/>\nOncologia e cure palliative pediatriche: alla ricerca di un\u2019integrazione possibile<\/p><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep-double sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-1\"><p>Il mondo dell\u2019oncologia pediatrica \u00e8 profondamente cambiato negli ultimi decenni, riuscendo ad offrire a bambini e adolescenti affetti da tumore un netto incremento della probabilit\u00e0 di guarigione e della sopravvivenza. Questo importante risultato ha determinato tuttavia un aumento della complessit\u00e0 assistenziale con percorsi di trattamento anche molto lunghi nel tempo, con l\u2019emergere di bisogni non solo clinici, ma anche psicologici, sociali, spirituali ed etici. La gestione di questa complessit\u00e0 \u00e8 ancora pi\u00f9 sfidante nei malati che presentano percorsi di malattia complicati da eventi avversi (es. tossicit\u00e0, recidive,\u2026) e in quelli che purtroppo vanno incontro ad una diagnosi di inguaribilit\u00e0 e di fine vita. Per identificare, valutare e rispondere a tutti questi bisogni \u00e8 necessario un approccio multidisciplinare e multispecialistico, che integri diverse conoscenze e competenze in grado di offrire la miglior qualit\u00e0 di cura (care) possibile. Questa integrazione \u00e8 identificata nella letteratura internazionale come la sinergia tra l\u2019oncologia pediatrica e le cure palliative pediatriche (CPP). Numerosi studi evidenziano come la precoce integrazione tra le due discipline abbia un significativo e positivo impatto sulla qualit\u00e0 di vita del bambino\/adolescente e della sua famiglia. Tuttavia, nella realt\u00e0, tale integrazione \u00e8 ancora lontana dall\u2019essere attuata, per numerosi motivi, primo fra tutti per la scarsa reciproca conoscenza, con una non ben chiara definizione di ruoli e competenze. Proprio con l\u2019obiettivo di favorire l\u2019integrazione tra oncologia pediatrica e CPP, l\u2019Associazione Italiana di Ematologia Oncologia Pediatrica (AIEOP), la Societ\u00e0 Italiana di Pediatria (SIP) e la Societ\u00e0 Italiana di Cure Palliative (SICP) hanno istituito un gruppo intersocietario formato da pediatri, infermieri e psicologici. Il gruppo ha definito come prioritaria la condivisione di un linguaggio comune, identificando i termini fondamentali nel dialogo tra le due discipline, e illustrandone il significato. Questo lavoro ha portato alla stesura di un glossario, frutto della revisione della letteratura e del confronto tra esperti, che rappresenta la base sulla quale costruire la sinergia per un approccio olistico al bambino\/adolescente affetto da tumore<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\"><p><a href=\"https:\/\/www.aieop.org\/web\/wp-content\/uploads\/2023\/05\/Glossario_ONC_CPP.pdf\" target=\"_blank\" rel=\"noopener\">Glossario_ONC_CPP<\/a><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-9450","post","type-post","status-publish","format-standard","hentry","category-in-evidenza"],"_links":{"self":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/comments?post=9450"}],"version-history":[{"count":1,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9450\/revisions"}],"predecessor-version":[{"id":9453,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/posts\/9450\/revisions\/9453"}],"wp:attachment":[{"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/media?parent=9450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/categories?post=9450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aieop.org\/web\/wp-json\/wp\/v2\/tags?post=9450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}